{"id":10160,"date":"2025-06-06T11:21:07","date_gmt":"2025-06-06T14:21:07","guid":{"rendered":"https:\/\/vocesdellangueyu.com.ar\/?p=10160"},"modified":"2025-06-06T11:21:08","modified_gmt":"2025-06-06T14:21:08","slug":"fda-luciano-pereyra-y-the-la-planta-confirmados","status":"publish","type":"post","link":"https:\/\/vocesdellangueyu.com.ar\/index.php\/2025\/06\/06\/fda-luciano-pereyra-y-the-la-planta-confirmados\/","title":{"rendered":"FDA: LUCIANO PEREYRA Y THE LA PLANTA, CONFIRMADOS"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage-1024x819.png\" alt=\"\" class=\"wp-image-10161\" srcset=\"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage-1024x819.png 1024w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage-300x240.png 300w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage-768x614.png 768w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage-1536x1229.png 1536w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage-1200x960.png 1200w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2025\/06\/collage.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>La ciudad se prepara para vivir uno de los eventos m\u00e1s esperados del a\u00f1o: la <strong>Fiesta Nacional del Ave de Raza<\/strong>, que este fin de semana ofrecer\u00e1 tres d\u00edas a puro espect\u00e1culo, m\u00fasica en vivo, desfiles y actividades para toda la familia.<\/p>\n\n\n\n<p><strong>Viernes 22 hs<\/strong><br>La fiesta comenzar\u00e1 el viernes por la noche con una grilla pensada para encender el escenario desde el primer minuto. Abrir\u00e1 la banda local <strong>Hasta las Manos<\/strong>, seguida por la presentaci\u00f3n de <strong>The La Planta<\/strong> como banda invitada. Para cerrar la jornada, la pista quedar\u00e1 en manos de los <strong>DJs locales<\/strong>, que har\u00e1n vibrar al p\u00fablico hasta la madrugada.<\/p>\n\n\n\n<p><strong>S\u00e1bado 21 hs<\/strong><br>La segunda jornada se perfila como la m\u00e1s destacada del fin de semana. A las 21 hs abrir\u00e1 la banda local <strong>La Kachy Band<\/strong>, para dar paso luego al talento de la cantante tandilense <strong>Juliana Lechini<\/strong>.<br>Uno de los momentos m\u00e1s esperados llegar\u00e1 con la presencia de <strong>Sergio Lapeg\u00fce<\/strong> y su banda <strong>Lapeg\u00fce Band<\/strong>, quienes ofrecer\u00e1n un show lleno de energ\u00eda. La noche contar\u00e1 adem\u00e1s con un artista de lujo: <strong>Luciano Pereyra<\/strong> ser\u00e1 el invitado especial que deleitar\u00e1 al p\u00fablico con su inconfundible voz.<br>El cierre, nuevamente, estar\u00e1 a cargo de los <strong>DJs locales<\/strong>.<\/p>\n\n\n\n<p><strong>Domingo<\/strong><br>El domingo se vivir\u00e1 la tradicional jornada de la fiesta con el <strong>desfile<\/strong>, el <strong>almuerzo<\/strong>, y a partir de las <strong>18 hs<\/strong>, el esperado evento de la <strong>Noche de la Coronaci\u00f3n<\/strong>, donde se coronar\u00e1 a las nuevas representantes de la fiesta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Entradas y puntos de venta<\/h3>\n\n\n\n<p><strong>Viernes<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Entrada general: <strong>$20.000<\/strong> (se puede pagar en 2 cuotas de $10.000).<\/li><li>Socios: <strong>20% de descuento<\/strong>.<\/li><\/ul>\n\n\n\n<p><strong>S\u00e1bado<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Campo: <strong>$35.000<\/strong> (3 cuotas: $15.000 + 2 de $10.000).<\/li><li>Campo pagando en contado: <strong>$30.000<\/strong>.<\/li><li>Platea: <strong>$60.000<\/strong> (3 cuotas de $20.000).<\/li><li>Socios: <strong>20% de descuento<\/strong> en todas las modalidades.<\/li><li>Pagando con <strong>tarjeta Elebar<\/strong>: 3 cuotas en todas las entradas.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Puntos de venta confirmados<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Veterinaria Mi Argentina<\/strong><\/li><li><strong>Kiosko Peter<\/strong><\/li><li><strong>Inmobiliaria de Fabio S\u00e1nchez<\/strong><br>Pr\u00f3ximamente se confirmar\u00e1n m\u00e1s puntos de venta en ciudades vecinas.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad se prepara para vivir uno de los eventos m\u00e1s esperados del a\u00f1o: la Fiesta Nacional del Ave de Raza, que este fin de semana ofrecer\u00e1 tres d\u00edas a puro espect\u00e1culo, m\u00fasica en vivo, desfiles y actividades para toda la familia. Viernes 22 hsLa fiesta comenzar\u00e1 el viernes por la noche con una grilla [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-10160","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paQJuC-2DS","_links":{"self":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10160"}],"version-history":[{"count":1,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10160\/revisions"}],"predecessor-version":[{"id":10162,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10160\/revisions\/10162"}],"wp:attachment":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}