{"id":1704,"date":"2020-11-17T16:11:17","date_gmt":"2020-11-17T19:11:17","guid":{"rendered":"http:\/\/vocesdellangueyu.com.ar\/?p=1704"},"modified":"2020-11-17T16:11:23","modified_gmt":"2020-11-17T19:11:23","slug":"rauch-podra-imprimir-los-carnet-de-conducir","status":"publish","type":"post","link":"https:\/\/vocesdellangueyu.com.ar\/index.php\/2020\/11\/17\/rauch-podra-imprimir-los-carnet-de-conducir\/","title":{"rendered":"RAUCH PODR\u00c1 IMPRIMIR LOS CARNET DE CONDUCIR"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2020\/11\/17-11-Giannatasio-segunda-parte.mp3\"><\/audio><figcaption>Sof\u00eda Giannatasio , Direcci\u00f3n de Inspecci\u00f3n<\/figcaption><\/figure>\n\n\n\n<p>La titular de la\n Direcci\u00f3n de Inspecci\u00f3n General Sof\u00eda Giannatasio confirm\u00f3\nque hoy la oficina atiende al p\u00fablico normalmente tras permanecer cerrada ayer\nen forma preventiva debido a que una trabajadora fue hisopada, por considerarse\ncaso sospechoso de coronavirus, \u201cse atiende \u00fanicamente a las personas con\nturnos\u201d.<\/p>\n\n\n\n<p>La funcionaria explic\u00f3 el avance que significar\u00e1 la\nincorporaci\u00f3n de una impresora de las licencias de conducir que el \u00e1rea puso en\nfuncionamiento el pasado viernes con la presencia de un funcionario del \u00e1rea de\nTransporte de la Provincia\nde Buenos Aires.<\/p>\n\n\n\n<p>Anteriormente se tomaba la documentaci\u00f3n se aprobaba el\ntr\u00e1mite y se enviaba a Tandil para imprimir la licencia, \u201cahora ese paso se va\na evitar, al tener la impresora el tr\u00e1mite ser\u00e1 m\u00e1s r\u00e1pido\u201d.<\/p>\n\n\n\n<p>\u201cSe necesita un tiempo de adaptaci\u00f3n al uso para que las\nlicencias se puedan aprobar e imprimir el mismo d\u00eda\u201d.<\/p>\n\n\n\n<p>Giannatasio tambi\u00e9n se refiri\u00f3 a los controles que se siguen\ndesarrollando desde la\n Direcci\u00f3n, e inform\u00f3 que se han incrementado las quejas por\nterrenos sucios o con pastizales y la presencia de roedores. <\/p>\n\n\n\n<p>Adem\u00e1s mencion\u00f3 que notan a la gente \u201cun poco m\u00e1s\nsusceptible\u201d en el cumplimiento de las normas sanitarias impuestas por el\ncoronavirus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La titular de la Direcci\u00f3n de Inspecci\u00f3n General Sof\u00eda Giannatasio confirm\u00f3 que hoy la oficina atiende al p\u00fablico normalmente tras permanecer cerrada ayer en forma preventiva debido a que una trabajadora fue hisopada, por considerarse caso sospechoso de coronavirus, \u201cse atiende \u00fanicamente a las personas con turnos\u201d. La funcionaria explic\u00f3 el avance que significar\u00e1 la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[17,11,13],"tags":[],"class_list":["post-1704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-rauch","category-rauch","category-sociedad-rauch"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2020\/11\/sof\u00eda.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paQJuC-ru","_links":{"self":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1704"}],"version-history":[{"count":1,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1704\/revisions"}],"predecessor-version":[{"id":1707,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1704\/revisions\/1707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media\/1705"}],"wp:attachment":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}