{"id":2018,"date":"2021-02-11T16:47:03","date_gmt":"2021-02-11T19:47:03","guid":{"rendered":"http:\/\/vocesdellangueyu.com.ar\/?p=2018"},"modified":"2021-02-11T16:47:06","modified_gmt":"2021-02-11T19:47:06","slug":"regreso-seguro-a-clases-liliana-cirullo-en-el-marco-estricto-del-plan-jurisdiccional-hoy-en-dia-ninguna-escuela-del-distrito-esta-en-condiciones-de-dar-un-presencialidad-que-garantice-el-cu","status":"publish","type":"post","link":"https:\/\/vocesdellangueyu.com.ar\/index.php\/2021\/02\/11\/regreso-seguro-a-clases-liliana-cirullo-en-el-marco-estricto-del-plan-jurisdiccional-hoy-en-dia-ninguna-escuela-del-distrito-esta-en-condiciones-de-dar-un-presencialidad-que-garantice-el-cu\/","title":{"rendered":"REGRESO SEGURO A CLASES: LILIANA  CIRULLO \u201cEN EL MARCO ESTRICTO DEL PLAN JURISDICCIONAL HOY EN D\u00cdA NINGUNA ESCUELA DEL DISTRITO EST\u00c1 EN CONDICIONES DE DAR UN PRESENCIALIDAD QUE GARANTICE EL CUIDADO Y  EL RESGUARDO\u201d."},"content":{"rendered":"\n<p>La titular\nde SUTEBA Rauch Liliana Cirullo asegur\u00f3 que desde el Frente de Unidad Docente\nadvierten que no hay escuelas en Rauch que est\u00e9n en condiciones de cumplir con\nlas exigencias que establecen los protocolos para la vuelta de la\npresencialidad en forma segura este a\u00f1o.<\/p>\n\n\n\n<p>\u201cEstamos\ntrabajando fuertemente, estamos preocupados y ocupados, hay que conocer y&nbsp; trabajar mucho los protocolos que van a\ndefinir si est\u00e1n en condiciones o no las instituciones educativas. En el marco\nestricto del plan Jurisdiccional hoy en d\u00eda ninguna escuela del distrito est\u00e1\nen condiciones de dar un presencialidad que garantice el cuidado y&nbsp; el resguardo\u201d.<\/p>\n\n\n\n<p>\u201cCuando\nhablamos&nbsp; del cumplimiento estricto del\nPlan Jurisdiccional falta el cumplimiento cabal\u201d.<\/p>\n\n\n\n<p>Cirulo\nconfirm\u00f3 que en este contexto, es posible que la vuelta de la actividad\npresencial en las escuelas se d\u00e9 sin respetar las normas sanitarias requeridas\ny adelant\u00f3 que las autoridades educativas del Distrito no hacen caso a las\nadvertencias del Frente de unidad Docente local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La titular de SUTEBA Rauch Liliana Cirullo asegur\u00f3 que desde el Frente de Unidad Docente advierten que no hay escuelas en Rauch que est\u00e9n en condiciones de cumplir con las exigencias que establecen los protocolos para la vuelta de la presencialidad en forma segura este a\u00f1o. \u201cEstamos trabajando fuertemente, estamos preocupados y ocupados, hay que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[17,11,13],"tags":[],"class_list":["post-2018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-rauch","category-rauch","category-sociedad-rauch"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2020\/08\/cirullio.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paQJuC-wy","_links":{"self":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2018"}],"version-history":[{"count":1,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2018\/revisions"}],"predecessor-version":[{"id":2019,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2018\/revisions\/2019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media\/777"}],"wp:attachment":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}