{"id":4445,"date":"2022-02-02T15:41:51","date_gmt":"2022-02-02T18:41:51","guid":{"rendered":"http:\/\/vocesdellangueyu.com.ar\/?p=4445"},"modified":"2022-02-02T15:41:55","modified_gmt":"2022-02-02T18:41:55","slug":"gandara-sica-de-turismo-a-comandar-un-area-diversa-y-compleja","status":"publish","type":"post","link":"https:\/\/vocesdellangueyu.com.ar\/index.php\/2022\/02\/02\/gandara-sica-de-turismo-a-comandar-un-area-diversa-y-compleja\/","title":{"rendered":"G\u00c1NDARA SICA, DE TURISMO A COMANDAR UN \u00c1REA DIVERSA Y COMPLEJA"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"blob:https:\/\/vocesdellangueyu.com.ar\/4afe2d15-3ffb-4846-a68c-9b52d1b1b7e7\"><\/audio><figcaption>Ferm\u00edn G\u00e1ndara  Sica, Subsecretario de Protecci\u00f3n Ciudadana <\/figcaption><\/figure>\n\n\n\n<p>Ferm\u00edn G\u00e1ndara Sica asumi\u00f3 formalmente el cargo de Subsecretario de Protecci\u00f3n Ciudadana para el que fue designado por el Intendente Municipal Maximiliano Suescun en la reestructuraci\u00f3n del gabinete anunciada la semana pasada.<br>\nDe desempe\u00f1arse como Director de Turismo por alg\u00fan tiempo, el funcionario ahora comandar\u00e1 un \u00e1rea muy heterog\u00e9nea, y que tendr\u00e1 bajo su \u00f3rbita diversas dependencias con problem\u00e1ticas variadas.<br>\nEstar\u00e1n bajo sus \u00f3rdenes la Direcci\u00f3n de Seguridad, el \u00e1rea de Tr\u00e1nsito, la Direcci\u00f3n Inspecci\u00f3n General, Bromatolog\u00eda y Defensa Civil entre otras.<br>\n\u201cLa Subsecretaria de Protecci\u00f3n Ciudadana es el \u00e1rea que tiene a cargo la coordinaci\u00f3n de todas las \u00e1reas que tienen  como objetivo proteger a la comunidad\u201d.<br>\nG\u00e1ndara Sica asegur\u00f3 que las dependencias bajo su \u00f3rbita cuentan con Directores y Subdirectores de carrera que son los que garantizar\u00e1n un buen desempe\u00f1o en cada uno de los sectores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ferm\u00edn G\u00e1ndara Sica asumi\u00f3 formalmente el cargo de Subsecretario de Protecci\u00f3n Ciudadana para el que fue designado por el Intendente Municipal Maximiliano Suescun en la reestructuraci\u00f3n del gabinete anunciada la semana pasada. De desempe\u00f1arse como Director de Turismo por alg\u00fan tiempo, el funcionario ahora comandar\u00e1 un \u00e1rea muy heterog\u00e9nea, y que tendr\u00e1 bajo su \u00f3rbita [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[11,13],"tags":[],"class_list":["post-4445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rauch","category-sociedad-rauch"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2021\/10\/gandara-sica-F.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paQJuC-19H","_links":{"self":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4445"}],"version-history":[{"count":1,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4445\/revisions"}],"predecessor-version":[{"id":4446,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4445\/revisions\/4446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media\/3883"}],"wp:attachment":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}