{"id":5428,"date":"2022-11-11T17:21:23","date_gmt":"2022-11-11T20:21:23","guid":{"rendered":"http:\/\/vocesdellangueyu.com.ar\/?p=5428"},"modified":"2022-11-11T17:21:30","modified_gmt":"2022-11-11T20:21:30","slug":"el-presidente-del-pj-local-considero-inoportuno-el-aumento-de-tasas-que-el-gobierno-instrumentara-a-fin-de-ano","status":"publish","type":"post","link":"https:\/\/vocesdellangueyu.com.ar\/index.php\/2022\/11\/11\/el-presidente-del-pj-local-considero-inoportuno-el-aumento-de-tasas-que-el-gobierno-instrumentara-a-fin-de-ano\/","title":{"rendered":"EL PRESIDENTE DEL PJ LOCAL CONSIDER\u00d3 \u2018INOPORTUNO\u2019 EL AUMENTO DE TASAS QUE EL GOBIERNO INSTRUMENTAR\u00c1 A FIN DE A\u00d1O"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2022\/11\/4bd3ae03-479e-4a3d-8cb2-eeec3bb522b8.jpg\" alt=\"\" class=\"wp-image-5429\" width=\"296\" height=\"332\" srcset=\"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2022\/11\/4bd3ae03-479e-4a3d-8cb2-eeec3bb522b8.jpg 378w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2022\/11\/4bd3ae03-479e-4a3d-8cb2-eeec3bb522b8-267x300.jpg 267w\" sizes=\"auto, (max-width: 296px) 100vw, 296px\" \/><figcaption>TISERA<\/figcaption><\/figure><\/div>\n\n\n\n<p>El titular del PJ local Emilio Tisera asegur\u00f3 esta ma\u00f1ana que \u2018no creo que el Municipio necesite 15 millones\u2019 para cerrar el a\u00f1o en alusi\u00f3n a lo que se recaudar\u00eda con la implementaci\u00f3n del 18 por ciento de aumento en las tasas en el \u00faltimo bimestre.<\/p>\n\n\n\n<p>El dirigente, que est\u00e1 asesorando al bloque del Frente de Todos en la materia y acompa\u00f1\u00f3 a los ediles al encuentro que mantuvieron con miembros de la Sociedad Rural para analizar el tema, agreg\u00f3 que \u2018van a recibir m\u00e1s de 230 millones que no ten\u00edan previsto\u2019 por coparticipaci\u00f3n.<\/p>\n\n\n\n<p>Tisera subray\u00f3 que \u2018tienen la plata de los contribuyentes rindiendo fondos en el banco\u2019 por lo que consider\u00f3 \u2018inoportuno\u2019 el aumento previsto por el Gobierno.<\/p>\n\n\n\n<p>\u2018Es claramente un aumento eleccionario\u2019 dice, para explicar que el aumento del 18 por ciento de diciembre servir\u00e1 para subir el piso sobre el cual se aplicar\u00e1 el incremento para el 2023, y de esa forma establecer una suba no tan impactante a principios de un a\u00f1o electoral.<\/p>\n\n\n\n<p>Subray\u00f3 que el oficialismo apela al \u2018versito\u2019 de decir que \u2018si no aumentamos no podemos prestar los servicios\u2026 y no creo que un Municipio que tiene un presupuesto de m\u00e1s de 1.300 millones de pesos, no pueda en los \u00faltimos dos meses del a\u00f1o prestar servicios porque le faltan 15 millones\u2019<\/p>\n\n\n\n<p>\u2018Es una mentira como una casa\u2026 no tiene ning\u00fan sustento pero tienen la mayor\u00eda para hacerlo\u2026\u2019 dijo Tisera.<\/p>\n\n\n\n<p>En otro \u00e1mbito de cosas, Tisera explic\u00f3 c\u00f3mo est\u00e1 trabajando el Partido Justicialista en el tramo final del a\u00f1o.<\/p>\n\n\n\n<p>\u2018Las mesas de producci\u00f3n, ambiente, educaci\u00f3n y salud siguen trabajando, han estado reunidas la semana pasada. Y como en proyecto en conjunto estamos trabajando en un bono contribuci\u00f3n para lo que es la remodelaci\u00f3n del busto al general Per\u00f3n\u2019 Dijo<\/p>\n\n\n\n<p>Adem\u00e1s anticip\u00f3 que el espacio tiene \u2018tres o cuatro\u2019 candidatos para encabezar la lista de las elecciones del a\u00f1o que viene para Intendente Municipal, aunque adelant\u00f3 que todav\u00eda no se barajan nombres.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"blob:http:\/\/vocesdellangueyu.com.ar\/0b5ba314-4ff6-4dcc-a245-79599853bd5e\"><\/audio><figcaption>TISERA<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"blob:http:\/\/vocesdellangueyu.com.ar\/310571c8-73ec-4de7-afde-89a9fded1961\"><\/audio><figcaption>TISERA<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El titular del PJ local Emilio Tisera asegur\u00f3 esta ma\u00f1ana que \u2018no creo que el Municipio necesite 15 millones\u2019 para cerrar el a\u00f1o en alusi\u00f3n a lo que se recaudar\u00eda con la implementaci\u00f3n del 18 por ciento de aumento en las tasas en el \u00faltimo bimestre. El dirigente, que est\u00e1 asesorando al bloque del Frente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-5428","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paQJuC-1py","_links":{"self":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5428"}],"version-history":[{"count":2,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5428\/revisions"}],"predecessor-version":[{"id":5433,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5428\/revisions\/5433"}],"wp:attachment":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}