{"id":5854,"date":"2022-12-12T17:38:27","date_gmt":"2022-12-12T20:38:27","guid":{"rendered":"http:\/\/vocesdellangueyu.com.ar\/?p=5854"},"modified":"2022-12-12T17:38:34","modified_gmt":"2022-12-12T20:38:34","slug":"demora-en-la-elevacion-del-presupuesto-lamarche-dijo-que-lo-vivimos-con-mucha-preocupacion-y-aseguro-que-es-una-estrategia-del-gobierno-para-no-dar-tiempo-a-un-est","status":"publish","type":"post","link":"https:\/\/vocesdellangueyu.com.ar\/index.php\/2022\/12\/12\/demora-en-la-elevacion-del-presupuesto-lamarche-dijo-que-lo-vivimos-con-mucha-preocupacion-y-aseguro-que-es-una-estrategia-del-gobierno-para-no-dar-tiempo-a-un-est\/","title":{"rendered":"DEMORA EN LA ELEVACI\u00d3N DEL PRESUPUESTO: LAMARCHE DIJO QUE \u201cLO VIVIMOS CON MUCHA PREOCUPACI\u00d3N\u201d Y ASEGUR\u00d3 QUE ES UNA \u201cESTRATEGIA\u201d DEL GOBIERNO PARA NO DAR TIEMPO A UN ESTUDIO \u201cCON PROFUNDIDAD\u201d"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2022\/12\/maria-pagina.jpg\" alt=\"\" class=\"wp-image-5855\" width=\"193\" height=\"208\" srcset=\"https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2022\/12\/maria-pagina.jpg 314w, https:\/\/vocesdellangueyu.com.ar\/wp-content\/uploads\/2022\/12\/maria-pagina-279x300.jpg 279w\" sizes=\"auto, (max-width: 193px) 100vw, 193px\" \/><figcaption>LAMARCHE<\/figcaption><\/figure><\/div>\n\n\n\n<p>La Presidenta del bloque de concejales del Frente de Todos Mar\u00eda Lamarche analiz\u00f3 esta ma\u00f1ana la demora del Departamento Ejecutivo local en enviar el proyecto de Ordenanza del C\u00e1lculo de Recursos y Presupuesto de Gastos para el 2023, y las ordenanzas Impositiva y Fiscal, en las que se establecen los aumentos de las tasas para el a\u00f1o entrante.<\/p>\n\n\n\n<p>El Gobierno ten\u00eda plazo para la presentaci\u00f3n de las iniciativas hasta el 30 de noviembre pasado, y Lamarche dijo que \u201cpara hacer un tratamiento responsable se necesita tiempo\u201d.<\/p>\n\n\n\n<p>La concejala entiende que se trata de una \u201cnueva modalidad\u201d adoptada por el Municipio desde la asunci\u00f3n de Axel Kicillof en la Provincia, ya que comenz\u00f3 a \u201cretrasar todo lo que m\u00e1s puede la presentaci\u00f3n del presupuesto\u201d.<\/p>\n\n\n\n<p>Sostiene que la intenci\u00f3n es \u201cllevar al tiempo l\u00edmite la presentaci\u00f3n para no dejar ning\u00fan tipo de margen para estudiar y analizar con profundidad el Presupuesto y la Ordenanza Impositiva\u201d.<\/p>\n\n\n\n<p>\u201cEs una falta de respeto que tienen y que no podemos comprender porque otros distritos lo han presentado en tiempo y forma (el 30 de octubre)\u201d se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Lamarche a\u00f1adi\u00f3 que si \u00e9sta situaci\u00f3n se hubiera dado en la gesti\u00f3n que encabez\u00f3 el fallecido ex Intendente Jorge Ugarte \u201chubiera sido un esc\u00e1ndalo\u201d.<\/p>\n\n\n\n<p>Anticip\u00f3 que desde la bancada de la oposici\u00f3n plantear\u00e1n la discusi\u00f3n sobre el pago del bono que est\u00e1n solicitando los trabajadores municipales para fin de a\u00f1o, y que se destinen recursos para que en 2023 se comience a implementar la carrera de enfermer\u00eda.<\/p>\n\n\n\n<p>Lamarche se refiri\u00f3 a la posibilidad que tendr\u00e1n de tratar los documentos en el recinto antes de fin de a\u00f1o<\/p>\n\n\n\n<p>\u2018Creo que el respeto tiene que ser ida y vuelta, ya tendr\u00edamos que estar&nbsp; tratando &nbsp;cual ser\u00eda ese aumento de tasas\u2019 Dijo. Y que en caso de que exista un nuevo pedido de prorroga el bloque de Frente de todos lo negar\u00eda &nbsp;\u2018porque nos parece una falta de respeto para el concejo deliberante\u2019<\/p>\n\n\n\n<p>Indic\u00f3 que el gobierno puede ser sancionado por el tribual de cuentas porque los plazos de presentaci\u00f3n est\u00e1n estipulados por ley<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"blob:http:\/\/vocesdellangueyu.com.ar\/cbd2cf78-77ac-4071-bdf0-5525c249454d\"><\/audio><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"blob:http:\/\/vocesdellangueyu.com.ar\/2abceddb-c7e5-45ec-a02a-ec1620926a92\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Presidenta del bloque de concejales del Frente de Todos Mar\u00eda Lamarche analiz\u00f3 esta ma\u00f1ana la demora del Departamento Ejecutivo local en enviar el proyecto de Ordenanza del C\u00e1lculo de Recursos y Presupuesto de Gastos para el 2023, y las ordenanzas Impositiva y Fiscal, en las que se establecen los aumentos de las tasas para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-5854","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paQJuC-1wq","_links":{"self":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5854"}],"version-history":[{"count":2,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5854\/revisions"}],"predecessor-version":[{"id":5859,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5854\/revisions\/5859"}],"wp:attachment":[{"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdellangueyu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}